{"id":5051,"date":"2025-02-20T09:48:57","date_gmt":"2025-02-20T09:48:57","guid":{"rendered":"https:\/\/cinegrell.ch\/?post_type=geraet&#038;p=5051"},"modified":"2025-06-30T13:35:28","modified_gmt":"2025-06-30T13:35:28","slug":"filter-4x4","status":"publish","type":"geraet","link":"https:\/\/cinegrell.ch\/en\/geraet\/filter-4x4\/","title":{"rendered":"Filter table"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Large selection of different filter types.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Open the corresponding filter size and use the search function to quickly find your desired filter.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\"><\/div>\n<\/div>\n\n\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary>Filter 4\u00d74<\/summary>\n<table id=\"tablepress-1\" class=\"tablepress tablepress-id-1\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">Brand<\/th><th class=\"column-2\">Type<\/th><th class=\"column-3\">Category<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Enhancing<\/td><td class=\"column-3\">Diffusion<\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Blue sg 1<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Blue sg 2<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Sunset sg 1<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Sunset sg 2<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-7\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">UV Haze 1<\/td><td class=\"column-3\">Diffusion<\/td>\n<\/tr>\n<tr class=\"row-8\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">UV Haze 2A<\/td><td class=\"column-3\">Diffusion<\/td>\n<\/tr>\n<tr class=\"row-9\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Chocolate 1<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-10\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Chocolate 2<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-11\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Chocolate 3<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-12\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Sepia 1<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-13\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Sepia 2<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-14\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Sepia 3<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-15\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Soft FX 1\/4<\/td><td class=\"column-3\">Diffusion<\/td>\n<\/tr>\n<tr class=\"row-16\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Straw 1<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-17\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Straw 2<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-18\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Straw 3<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-19\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Diffusion 1<\/td><td class=\"column-3\">Diffusion<\/td>\n<\/tr>\n<tr class=\"row-20\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Diffusion 2<\/td><td class=\"column-3\">Diffusion<\/td>\n<\/tr>\n<tr class=\"row-21\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Diffusion 3<\/td><td class=\"column-3\">Diffusion<\/td>\n<\/tr>\n<tr class=\"row-22\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Diffusion 4<\/td><td class=\"column-3\">Diffusion<\/td>\n<\/tr>\n<tr class=\"row-23\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Diffusion 5<\/td><td class=\"column-3\">Diffusion<\/td>\n<\/tr>\n<tr class=\"row-24\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Black Diffusion FX 1\/4<\/td><td class=\"column-3\">Diffusion<\/td>\n<\/tr>\n<tr class=\"row-25\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Black Diffusion FX 1\/2<\/td><td class=\"column-3\">Diffusion<\/td>\n<\/tr>\n<tr class=\"row-26\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Black Diffusion FX 1<\/td><td class=\"column-3\">Diffusion<\/td>\n<\/tr>\n<tr class=\"row-27\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Black Diffusion FX 2<\/td><td class=\"column-3\">Diffusion<\/td>\n<\/tr>\n<tr class=\"row-28\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Low Light Diffusion LLD<\/td><td class=\"column-3\">Diffusion<\/td>\n<\/tr>\n<tr class=\"row-29\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Fog 1\/2<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-30\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Day for Night cool<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-31\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Day for Night mono<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-32\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">85<\/td><td class=\"column-3\">Analogue<\/td>\n<\/tr>\n<tr class=\"row-33\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">85 ND 0.3<\/td><td class=\"column-3\">Analogue<\/td>\n<\/tr>\n<tr class=\"row-34\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">85 ND 0.6<\/td><td class=\"column-3\">Analogue<\/td>\n<\/tr>\n<tr class=\"row-35\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">85 ND 0.9<\/td><td class=\"column-3\">Analogue<\/td>\n<\/tr>\n<tr class=\"row-36\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">85 Pole<\/td><td class=\"column-3\">Analogue<\/td>\n<\/tr>\n<tr class=\"row-37\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">80 A<\/td><td class=\"column-3\">Analogue<\/td>\n<\/tr>\n<tr class=\"row-38\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">80 B<\/td><td class=\"column-3\">Analogue<\/td>\n<\/tr>\n<tr class=\"row-39\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">80 C<\/td><td class=\"column-3\">Analogue<\/td>\n<\/tr>\n<tr class=\"row-40\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">80 D<\/td><td class=\"column-3\">Analogue<\/td>\n<\/tr>\n<tr class=\"row-41\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Softnet 2<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-42\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Softnet 4<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-43\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Black Dot 1<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-44\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Black Dot 2<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-45\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Black Dot 3<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-46\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Black Dot 4<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-47\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Black Dot 5<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-1 from cache --><\/details>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary>Filter 4\u00d75.65<\/summary>\n<table id=\"tablepress-3\" class=\"tablepress tablepress-id-3\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">Brand<\/th><th class=\"column-2\">Type<\/th><th class=\"column-3\">Category<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\">Tailor<\/td><td class=\"column-2\">Clear<\/td><td class=\"column-3\">Pole &amp; Clear<\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">Formatt<\/td><td class=\"column-2\">Clear<\/td><td class=\"column-3\">Pole &amp; Clear<\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">Tailor<\/td><td class=\"column-2\">True Pole<\/td><td class=\"column-3\">Pole &amp; Clear<\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">Arri Rota Pol Filter Frame<\/td><td class=\"column-2\">Rota Pol Linear<\/td><td class=\"column-3\">Pole &amp; Clear<\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\">Tailor<\/td><td class=\"column-2\">True Pole Linear<\/td><td class=\"column-3\">Pole &amp; Clear<\/td>\n<\/tr>\n<tr class=\"row-7\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Polariser<\/td><td class=\"column-3\">Pole &amp; Clear<\/td>\n<\/tr>\n<tr class=\"row-8\">\n\t<td class=\"column-1\">Formatt<\/td><td class=\"column-2\">Polariser<\/td><td class=\"column-3\">Pole &amp; Clear<\/td>\n<\/tr>\n<tr class=\"row-9\">\n\t<td class=\"column-1\">Tailor<\/td><td class=\"column-2\">ND 0.3<\/td><td class=\"column-3\">ND<\/td>\n<\/tr>\n<tr class=\"row-10\">\n\t<td class=\"column-1\">Tailor<\/td><td class=\"column-2\">ND 0.6<\/td><td class=\"column-3\">ND<\/td>\n<\/tr>\n<tr class=\"row-11\">\n\t<td class=\"column-1\">Tailor<\/td><td class=\"column-2\">ND 0.9<\/td><td class=\"column-3\">ND<\/td>\n<\/tr>\n<tr class=\"row-12\">\n\t<td class=\"column-1\">Tailor<\/td><td class=\"column-2\">ND 1.2<\/td><td class=\"column-3\">ND<\/td>\n<\/tr>\n<tr class=\"row-13\">\n\t<td class=\"column-1\">Tailor<\/td><td class=\"column-2\">IR ND 0.3<\/td><td class=\"column-3\">ND<\/td>\n<\/tr>\n<tr class=\"row-14\">\n\t<td class=\"column-1\">Tailor<\/td><td class=\"column-2\">IR ND 0.6<\/td><td class=\"column-3\">ND<\/td>\n<\/tr>\n<tr class=\"row-15\">\n\t<td class=\"column-1\">Tailor<\/td><td class=\"column-2\">IR ND 0.9<\/td><td class=\"column-3\">ND<\/td>\n<\/tr>\n<tr class=\"row-16\">\n\t<td class=\"column-1\">Tailor<\/td><td class=\"column-2\">IR ND 1.2<\/td><td class=\"column-3\">ND<\/td>\n<\/tr>\n<tr class=\"row-17\">\n\t<td class=\"column-1\">Tailor<\/td><td class=\"column-2\">IR ND 1.5<\/td><td class=\"column-3\">ND<\/td>\n<\/tr>\n<tr class=\"row-18\">\n\t<td class=\"column-1\">Tailor<\/td><td class=\"column-2\">IR ND 1.8<\/td><td class=\"column-3\">ND<\/td>\n<\/tr>\n<tr class=\"row-19\">\n\t<td class=\"column-1\">Tailor<\/td><td class=\"column-2\">IR ND 2.1<\/td><td class=\"column-3\">ND<\/td>\n<\/tr>\n<tr class=\"row-20\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">IR ND 0.3<\/td><td class=\"column-3\">ND<\/td>\n<\/tr>\n<tr class=\"row-21\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">IR ND 0.6<\/td><td class=\"column-3\">ND<\/td>\n<\/tr>\n<tr class=\"row-22\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">IR ND 0.9<\/td><td class=\"column-3\">ND<\/td>\n<\/tr>\n<tr class=\"row-23\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">IR ND 1.2<\/td><td class=\"column-3\">ND<\/td>\n<\/tr>\n<tr class=\"row-24\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">IR ND 1.5<\/td><td class=\"column-3\">ND<\/td>\n<\/tr>\n<tr class=\"row-25\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">IR ND 1.8<\/td><td class=\"column-3\">ND<\/td>\n<\/tr>\n<tr class=\"row-26\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">IR ND 2.1<\/td><td class=\"column-3\">ND<\/td>\n<\/tr>\n<tr class=\"row-27\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">ND 0.3<\/td><td class=\"column-3\">ND<\/td>\n<\/tr>\n<tr class=\"row-28\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">ND 0.6<\/td><td class=\"column-3\">ND<\/td>\n<\/tr>\n<tr class=\"row-29\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">ND 0.9<\/td><td class=\"column-3\">ND<\/td>\n<\/tr>\n<tr class=\"row-30\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">ND 1.2<\/td><td class=\"column-3\">ND<\/td>\n<\/tr>\n<tr class=\"row-31\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">ND 1.5<\/td><td class=\"column-3\">ND<\/td>\n<\/tr>\n<tr class=\"row-32\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">ND 1.8<\/td><td class=\"column-3\">ND<\/td>\n<\/tr>\n<tr class=\"row-33\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">ND 2.1<\/td><td class=\"column-3\">ND<\/td>\n<\/tr>\n<tr class=\"row-34\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">ND sg 0.3 horizontal<\/td><td class=\"column-3\">ND<\/td>\n<\/tr>\n<tr class=\"row-35\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">ND sg 0.6 horizontal<\/td><td class=\"column-3\">ND<\/td>\n<\/tr>\n<tr class=\"row-36\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">ND sg 0.9 horizontal<\/td><td class=\"column-3\">ND<\/td>\n<\/tr>\n<tr class=\"row-37\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">ND sg 1.2 horizontal<\/td><td class=\"column-3\">ND<\/td>\n<\/tr>\n<tr class=\"row-38\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">ND hg 0.3 horizontal<\/td><td class=\"column-3\">ND<\/td>\n<\/tr>\n<tr class=\"row-39\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">ND hg 0.6 horizontal<\/td><td class=\"column-3\">ND<\/td>\n<\/tr>\n<tr class=\"row-40\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">ND hg 0.9 horizontal<\/td><td class=\"column-3\">ND<\/td>\n<\/tr>\n<tr class=\"row-41\">\n\t<td class=\"column-1\">Tailor<\/td><td class=\"column-2\">ND sg 0.3 horizontal<\/td><td class=\"column-3\">ND<\/td>\n<\/tr>\n<tr class=\"row-42\">\n\t<td class=\"column-1\">Tailor<\/td><td class=\"column-2\">ND sg 0.6 horizontal<\/td><td class=\"column-3\">ND<\/td>\n<\/tr>\n<tr class=\"row-43\">\n\t<td class=\"column-1\">Tailor<\/td><td class=\"column-2\">ND sg 0.9 horizontal<\/td><td class=\"column-3\">ND<\/td>\n<\/tr>\n<tr class=\"row-44\">\n\t<td class=\"column-1\">Tailor<\/td><td class=\"column-2\">ND hg 0.3 horizontal<\/td><td class=\"column-3\">ND<\/td>\n<\/tr>\n<tr class=\"row-45\">\n\t<td class=\"column-1\">Tailor<\/td><td class=\"column-2\">ND hg 0.6 horizontal<\/td><td class=\"column-3\">ND<\/td>\n<\/tr>\n<tr class=\"row-46\">\n\t<td class=\"column-1\">Tailor<\/td><td class=\"column-2\">ND hg 0.9 horizontal<\/td><td class=\"column-3\">ND<\/td>\n<\/tr>\n<tr class=\"row-47\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">ND sg 0.3 vertical<\/td><td class=\"column-3\">ND<\/td>\n<\/tr>\n<tr class=\"row-48\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">ND sg 0.6 vertical<\/td><td class=\"column-3\">ND<\/td>\n<\/tr>\n<tr class=\"row-49\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">ND sg 0.9 vertical<\/td><td class=\"column-3\">ND<\/td>\n<\/tr>\n<tr class=\"row-50\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">ND hg 0.3 vertical<\/td><td class=\"column-3\">ND<\/td>\n<\/tr>\n<tr class=\"row-51\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">ND hg 0.6 vertical<\/td><td class=\"column-3\">ND<\/td>\n<\/tr>\n<tr class=\"row-52\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">ND hg 0.9 vertical<\/td><td class=\"column-3\">ND<\/td>\n<\/tr>\n<tr class=\"row-53\">\n\t<td class=\"column-1\">Formatt<\/td><td class=\"column-2\">ND Blender 0.3 vertical<\/td><td class=\"column-3\">ND<\/td>\n<\/tr>\n<tr class=\"row-54\">\n\t<td class=\"column-1\">Formatt<\/td><td class=\"column-2\">ND Blender 0.6 vertical<\/td><td class=\"column-3\">ND<\/td>\n<\/tr>\n<tr class=\"row-55\">\n\t<td class=\"column-1\">Formatt<\/td><td class=\"column-2\">ND Blender 0.9 vertical<\/td><td class=\"column-3\">ND<\/td>\n<\/tr>\n<tr class=\"row-56\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Per crap 1\/2<\/td><td class=\"column-3\">Diffusion<\/td>\n<\/tr>\n<tr class=\"row-57\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Per crap 1<\/td><td class=\"column-3\">Diffusion<\/td>\n<\/tr>\n<tr class=\"row-58\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Black Pro Mist 1\/8<\/td><td class=\"column-3\">Diffusion<\/td>\n<\/tr>\n<tr class=\"row-59\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Black Pro Mist 1\/4<\/td><td class=\"column-3\">Diffusion<\/td>\n<\/tr>\n<tr class=\"row-60\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Black Pro Mist 1\/2<\/td><td class=\"column-3\">Diffusion<\/td>\n<\/tr>\n<tr class=\"row-61\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Black Pro Mist 1<\/td><td class=\"column-3\">Diffusion<\/td>\n<\/tr>\n<tr class=\"row-62\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Black Pro Mist 2<\/td><td class=\"column-3\">Diffusion<\/td>\n<\/tr>\n<tr class=\"row-63\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Soft FX 1\/2<\/td><td class=\"column-3\">Diffusion<\/td>\n<\/tr>\n<tr class=\"row-64\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Soft FX 1<\/td><td class=\"column-3\">Diffusion<\/td>\n<\/tr>\n<tr class=\"row-65\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Soft FX 2<\/td><td class=\"column-3\">Diffusion<\/td>\n<\/tr>\n<tr class=\"row-66\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Soft FX 3<\/td><td class=\"column-3\">Diffusion<\/td>\n<\/tr>\n<tr class=\"row-67\">\n\t<td class=\"column-1\">Tailor<\/td><td class=\"column-2\">Digicon 1\/8<\/td><td class=\"column-3\">Diffusion<\/td>\n<\/tr>\n<tr class=\"row-68\">\n\t<td class=\"column-1\">Tailor<\/td><td class=\"column-2\">Digicon 1\/4<\/td><td class=\"column-3\">Diffusion<\/td>\n<\/tr>\n<tr class=\"row-69\">\n\t<td class=\"column-1\">Tailor<\/td><td class=\"column-2\">Digicon 1\/2<\/td><td class=\"column-3\">Diffusion<\/td>\n<\/tr>\n<tr class=\"row-70\">\n\t<td class=\"column-1\">Tailor<\/td><td class=\"column-2\">Hollywood Black Magic 1\/8<\/td><td class=\"column-3\">Diffusion<\/td>\n<\/tr>\n<tr class=\"row-71\">\n\t<td class=\"column-1\">Tailor<\/td><td class=\"column-2\">Hollywood Black Magic 1\/4<\/td><td class=\"column-3\">Diffusion<\/td>\n<\/tr>\n<tr class=\"row-72\">\n\t<td class=\"column-1\">Tailor<\/td><td class=\"column-2\">Hollywood Black Magic 1\/2<\/td><td class=\"column-3\">Diffusion<\/td>\n<\/tr>\n<tr class=\"row-73\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">IR T1<\/td><td class=\"column-3\">ND<\/td>\n<\/tr>\n<tr class=\"row-74\">\n\t<td class=\"column-1\">Tailor<\/td><td class=\"column-2\">Black Frost 1\/8<\/td><td class=\"column-3\">Diffusion<\/td>\n<\/tr>\n<tr class=\"row-75\">\n\t<td class=\"column-1\">Tailor<\/td><td class=\"column-2\">Black Frost 1\/4<\/td><td class=\"column-3\">Diffusion<\/td>\n<\/tr>\n<tr class=\"row-76\">\n\t<td class=\"column-1\">Tailor<\/td><td class=\"column-2\">Black Frost 1\/2<\/td><td class=\"column-3\">Diffusion<\/td>\n<\/tr>\n<tr class=\"row-77\">\n\t<td class=\"column-1\">Formatt<\/td><td class=\"column-2\">Chocolate 1<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-78\">\n\t<td class=\"column-1\">Tailor<\/td><td class=\"column-2\">Gold 1<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-79\">\n\t<td class=\"column-1\">Tailor<\/td><td class=\"column-2\">Gold 2<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-80\">\n\t<td class=\"column-1\">Tailor<\/td><td class=\"column-2\">Gold 3<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-81\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Low Contrast 1\/8<\/td><td class=\"column-3\">Contrast<\/td>\n<\/tr>\n<tr class=\"row-82\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Low Contrast 1\/4<\/td><td class=\"column-3\">Contrast<\/td>\n<\/tr>\n<tr class=\"row-83\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Low Contrast 1\/2<\/td><td class=\"column-3\">Contrast<\/td>\n<\/tr>\n<tr class=\"row-84\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Low Contrast 1<\/td><td class=\"column-3\">Contrast<\/td>\n<\/tr>\n<tr class=\"row-85\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Low Contrast 2<\/td><td class=\"column-3\">Contrast<\/td>\n<\/tr>\n<tr class=\"row-86\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Low Contrast 3<\/td><td class=\"column-3\">Contrast<\/td>\n<\/tr>\n<tr class=\"row-87\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Low Contrast 4<\/td><td class=\"column-3\">Contrast<\/td>\n<\/tr>\n<tr class=\"row-88\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Low Contrast 5<\/td><td class=\"column-3\">Contrast<\/td>\n<\/tr>\n<tr class=\"row-89\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Sunset Grade 1 vertical<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-90\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Sunset Grade 2 vertical<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-91\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Sunset Grade 3 vertical<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-92\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Fog 1<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-93\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Fog 2<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-94\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Fog 3<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-95\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Fog 4<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-96\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Fog 5<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-97\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Star 4pt 2mm<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-98\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Star 4pt 3mm<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-99\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Star 4pt 4mm<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-100\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Star 6pt 2mm<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-101\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Star 6pt 4mm<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-102\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Star 8pt 2mm<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-103\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Star 8pt 3mm<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-104\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Star 8pt 4mm<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-105\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">85C<\/td><td class=\"column-3\">Analogue<\/td>\n<\/tr>\n<tr class=\"row-106\">\n\t<td class=\"column-1\">Formatt<\/td><td class=\"column-2\">80B<\/td><td class=\"column-3\">Analogue<\/td>\n<\/tr>\n<tr class=\"row-107\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">85<\/td><td class=\"column-3\">Analogue<\/td>\n<\/tr>\n<tr class=\"row-108\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">85 ND 0.3<\/td><td class=\"column-3\">Analogue<\/td>\n<\/tr>\n<tr class=\"row-109\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">85 ND 0.6<\/td><td class=\"column-3\">Analogue<\/td>\n<\/tr>\n<tr class=\"row-110\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">85 ND 0.9<\/td><td class=\"column-3\">Analogue<\/td>\n<\/tr>\n<tr class=\"row-111\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">85 Pole<\/td><td class=\"column-3\">Analogue<\/td>\n<\/tr>\n<tr class=\"row-112\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Black Diffusion FX 1\/4<\/td><td class=\"column-3\">Diffusion<\/td>\n<\/tr>\n<tr class=\"row-113\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Black Diffusion FX 1\/2<\/td><td class=\"column-3\">Diffusion<\/td>\n<\/tr>\n<tr class=\"row-114\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Black Diffusion FX 1<\/td><td class=\"column-3\">Diffusion<\/td>\n<\/tr>\n<tr class=\"row-115\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Mica glass 1\/8<\/td><td class=\"column-3\">Diffusion<\/td>\n<\/tr>\n<tr class=\"row-116\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Mica glass 1\/4<\/td><td class=\"column-3\">Diffusion<\/td>\n<\/tr>\n<tr class=\"row-117\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Mica glass 1\/2<\/td><td class=\"column-3\">Diffusion<\/td>\n<\/tr>\n<tr class=\"row-118\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Ultra Contrast 1\/8<\/td><td class=\"column-3\">Contrast<\/td>\n<\/tr>\n<tr class=\"row-119\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Ultra Contrast 1\/4<\/td><td class=\"column-3\">Contrast<\/td>\n<\/tr>\n<tr class=\"row-120\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Ultra Contrast 1\/2<\/td><td class=\"column-3\">Contrast<\/td>\n<\/tr>\n<tr class=\"row-121\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Ultra Contrast 1<\/td><td class=\"column-3\">Contrast<\/td>\n<\/tr>\n<tr class=\"row-122\">\n\t<td class=\"column-1\">Tailor<\/td><td class=\"column-2\">One Stop Linear Polariser<\/td><td class=\"column-3\">Pole &amp; Clear<\/td>\n<\/tr>\n<tr class=\"row-123\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Antique Suede 1<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-124\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Antique Suede 2<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-125\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Antique Suede 3<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-126\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Enhancing<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-127\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Gold Diffusion FX 1\/4<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-128\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Gold Diffusion FX 1\/2<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-129\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Gold Diffusion FX 1<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-130\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Gold Diffusion FX 2<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-131\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Gold Diffusion FX 3<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-132\">\n\t<td class=\"column-1\">Tailor<\/td><td class=\"column-2\">True Streak blue 1mm<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-133\">\n\t<td class=\"column-1\">Tailor<\/td><td class=\"column-2\">True Streak blue 2mm<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-134\">\n\t<td class=\"column-1\">Tailor<\/td><td class=\"column-2\">True Streak blue 3mm<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-135\">\n\t<td class=\"column-1\">Tailor<\/td><td class=\"column-2\">True Streak clear 1mm<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-136\">\n\t<td class=\"column-1\">Tailor<\/td><td class=\"column-2\">True Streak clear 2mm<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-137\">\n\t<td class=\"column-1\">Tailor<\/td><td class=\"column-2\">True Streak clear 3mm<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-138\">\n\t<td class=\"column-1\">Tailor<\/td><td class=\"column-2\">Low Contrast 1\/8<\/td><td class=\"column-3\">Contrast<\/td>\n<\/tr>\n<tr class=\"row-139\">\n\t<td class=\"column-1\">Tailor<\/td><td class=\"column-2\">Low Contrast 1\/4<\/td><td class=\"column-3\">Contrast<\/td>\n<\/tr>\n<tr class=\"row-140\">\n\t<td class=\"column-1\">Tailor<\/td><td class=\"column-2\">Low Contrast 1\/2<\/td><td class=\"column-3\">Contrast<\/td>\n<\/tr>\n<tr class=\"row-141\">\n\t<td class=\"column-1\">Tailor<\/td><td class=\"column-2\">Low Contrast 1<\/td><td class=\"column-3\">Contrast<\/td>\n<\/tr>\n<tr class=\"row-142\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Perlascent 1\/8<\/td><td class=\"column-3\">Diffusion<\/td>\n<\/tr>\n<tr class=\"row-143\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Perlascent 1\/4<\/td><td class=\"column-3\">Diffusion<\/td>\n<\/tr>\n<tr class=\"row-144\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Perlascent 1\/2<\/td><td class=\"column-3\">Diffusion<\/td>\n<\/tr>\n<tr class=\"row-145\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Perlascent 1<\/td><td class=\"column-3\">Diffusion<\/td>\n<\/tr>\n<tr class=\"row-146\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Perlascent 2<\/td><td class=\"column-3\">Diffusion<\/td>\n<\/tr>\n<tr class=\"row-147\">\n\t<td class=\"column-1\">Tailor<\/td><td class=\"column-2\">Attenuator 0.3 horizontal<\/td><td class=\"column-3\">ND<\/td>\n<\/tr>\n<tr class=\"row-148\">\n\t<td class=\"column-1\">Tailor<\/td><td class=\"column-2\">Attenuator 0.6 horizontal<\/td><td class=\"column-3\">ND<\/td>\n<\/tr>\n<tr class=\"row-149\">\n\t<td class=\"column-1\">Tailor<\/td><td class=\"column-2\">Attenuator 0.9 horizontal<\/td><td class=\"column-3\">ND<\/td>\n<\/tr>\n<tr class=\"row-150\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Black Satin 1\/2<\/td><td class=\"column-3\">Diffusion<\/td>\n<\/tr>\n<tr class=\"row-151\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Black Satin 1<\/td><td class=\"column-3\">Diffusion<\/td>\n<\/tr>\n<tr class=\"row-152\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Black Satin 2<\/td><td class=\"column-3\">Diffusion<\/td>\n<\/tr>\n<tr class=\"row-153\">\n\t<td class=\"column-1\">Tailor<\/td><td class=\"column-2\">One Stop Circular Polariser<\/td><td class=\"column-3\">Pole &amp; Clear<\/td>\n<\/tr>\n<tr class=\"row-154\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">81EF<\/td><td class=\"column-3\">Analogue<\/td>\n<\/tr>\n<tr class=\"row-155\">\n\t<td class=\"column-1\">Tailor<\/td><td class=\"column-2\">Classic Soft 1\/4<\/td><td class=\"column-3\">Diffusion<\/td>\n<\/tr>\n<tr class=\"row-156\">\n\t<td class=\"column-1\">Tailor<\/td><td class=\"column-2\">Classic Soft 1\/8<\/td><td class=\"column-3\">Diffusion<\/td>\n<\/tr>\n<tr class=\"row-157\">\n\t<td class=\"column-1\">Tailor<\/td><td class=\"column-2\">Classic Soft 1\/2<\/td><td class=\"column-3\">Diffusion<\/td>\n<\/tr>\n<tr class=\"row-158\">\n\t<td class=\"column-1\">Tailor<\/td><td class=\"column-2\">Classic Soft 1<\/td><td class=\"column-3\">Diffusion<\/td>\n<\/tr>\n<tr class=\"row-159\">\n\t<td class=\"column-1\">Tailor<\/td><td class=\"column-2\">Classic Soft 2<\/td><td class=\"column-3\">Diffusion<\/td>\n<\/tr>\n<tr class=\"row-160\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Per muck 1\/4<\/td><td class=\"column-3\">Diffusion<\/td>\n<\/tr>\n<tr class=\"row-161\">\n\t<td class=\"column-1\">TIffen<\/td><td class=\"column-2\">Per Mist 1\/8<\/td><td class=\"column-3\">Diffusion<\/td>\n<\/tr>\n<tr class=\"row-162\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">85 ND 1.2<\/td><td class=\"column-3\">Analogue<\/td>\n<\/tr>\n<tr class=\"row-163\">\n\t<td class=\"column-1\">Cine Prism FX<\/td><td class=\"column-2\">Clear Optical Flat<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-164\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Black Satin 1\/4<\/td><td class=\"column-3\">Diffusion<\/td>\n<\/tr>\n<tr class=\"row-165\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Black Satin 1\/8<\/td><td class=\"column-3\">Diffusion<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-3 from cache --><\/details>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary>Filter 6\u00d76<\/summary>\n<table id=\"tablepress-4\" class=\"tablepress tablepress-id-4\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">Brand<\/th><th class=\"column-2\">Type<\/th><th class=\"column-3\">Category<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\">Tailor<\/td><td class=\"column-2\">True Pole<\/td><td class=\"column-3\">Pole &amp; Clear<\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">Tailor<\/td><td class=\"column-2\">True Pole Circular<\/td><td class=\"column-3\">Pole &amp; Clear<\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Ultrapol Circular<\/td><td class=\"column-3\">Pole &amp; Clear<\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">Tailor<\/td><td class=\"column-2\">Clear<\/td><td class=\"column-3\">Pole &amp; Clear<\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Clear<\/td><td class=\"column-3\">Pole &amp; Clear<\/td>\n<\/tr>\n<tr class=\"row-7\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">ND 0.3<\/td><td class=\"column-3\">ND<\/td>\n<\/tr>\n<tr class=\"row-8\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">ND 0.6<\/td><td class=\"column-3\">ND<\/td>\n<\/tr>\n<tr class=\"row-9\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">ND 0.9<\/td><td class=\"column-3\">ND<\/td>\n<\/tr>\n<tr class=\"row-10\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">ND 1.2<\/td><td class=\"column-3\">ND<\/td>\n<\/tr>\n<tr class=\"row-11\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">ND 1.5<\/td><td class=\"column-3\">ND<\/td>\n<\/tr>\n<tr class=\"row-12\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">ND 1.8<\/td><td class=\"column-3\">ND<\/td>\n<\/tr>\n<tr class=\"row-13\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">ND 2.1<\/td><td class=\"column-3\">ND<\/td>\n<\/tr>\n<tr class=\"row-14\">\n\t<td class=\"column-1\">Tailor<\/td><td class=\"column-2\">Platinum IR ND 0.3<\/td><td class=\"column-3\">ND<\/td>\n<\/tr>\n<tr class=\"row-15\">\n\t<td class=\"column-1\">Tailor<\/td><td class=\"column-2\">Platinum IR ND 0.6<\/td><td class=\"column-3\">ND<\/td>\n<\/tr>\n<tr class=\"row-16\">\n\t<td class=\"column-1\">Tailor<\/td><td class=\"column-2\">Platinum IR ND 0.9<\/td><td class=\"column-3\">ND<\/td>\n<\/tr>\n<tr class=\"row-17\">\n\t<td class=\"column-1\">Tailor<\/td><td class=\"column-2\">Platinum IR ND 1.2<\/td><td class=\"column-3\">ND<\/td>\n<\/tr>\n<tr class=\"row-18\">\n\t<td class=\"column-1\">Tailor<\/td><td class=\"column-2\">Platinum IR ND 1.5<\/td><td class=\"column-3\">ND<\/td>\n<\/tr>\n<tr class=\"row-19\">\n\t<td class=\"column-1\">Tailor<\/td><td class=\"column-2\">Platinum IR ND 1.8<\/td><td class=\"column-3\">ND<\/td>\n<\/tr>\n<tr class=\"row-20\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">IR ND 0.3<\/td><td class=\"column-3\">ND<\/td>\n<\/tr>\n<tr class=\"row-21\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">IR ND 0.6<\/td><td class=\"column-3\">ND<\/td>\n<\/tr>\n<tr class=\"row-22\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">IR ND 0.9<\/td><td class=\"column-3\">ND<\/td>\n<\/tr>\n<tr class=\"row-23\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">IR ND 1.2<\/td><td class=\"column-3\">ND<\/td>\n<\/tr>\n<tr class=\"row-24\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">IR ND 1.5<\/td><td class=\"column-3\">ND<\/td>\n<\/tr>\n<tr class=\"row-25\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">IR ND 1.8<\/td><td class=\"column-3\">ND<\/td>\n<\/tr>\n<tr class=\"row-26\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">ND sg 0.3<\/td><td class=\"column-3\">ND<\/td>\n<\/tr>\n<tr class=\"row-27\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">ND sg 0.6<\/td><td class=\"column-3\">ND<\/td>\n<\/tr>\n<tr class=\"row-28\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">ND sg 0.9<\/td><td class=\"column-3\">ND<\/td>\n<\/tr>\n<tr class=\"row-29\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">ND sg 1.2<\/td><td class=\"column-3\">ND<\/td>\n<\/tr>\n<tr class=\"row-30\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">ND hg 0.3<\/td><td class=\"column-3\">ND<\/td>\n<\/tr>\n<tr class=\"row-31\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">ND hg 0.6<\/td><td class=\"column-3\">ND<\/td>\n<\/tr>\n<tr class=\"row-32\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">ND hg 0.9<\/td><td class=\"column-3\">ND<\/td>\n<\/tr>\n<tr class=\"row-33\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">ND hg 1.2<\/td><td class=\"column-3\">ND<\/td>\n<\/tr>\n<tr class=\"row-34\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Soft FX 1\/2<\/td><td class=\"column-3\">Diffusion<\/td>\n<\/tr>\n<tr class=\"row-35\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Soft FX 1<\/td><td class=\"column-3\">Diffusion<\/td>\n<\/tr>\n<tr class=\"row-36\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Soft FX 2<\/td><td class=\"column-3\">Diffusion<\/td>\n<\/tr>\n<tr class=\"row-37\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Soft FX 3<\/td><td class=\"column-3\">Diffusion<\/td>\n<\/tr>\n<tr class=\"row-38\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Black Pro Mist 1\/8<\/td><td class=\"column-3\">Diffusion<\/td>\n<\/tr>\n<tr class=\"row-39\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Black Pro Mist 1\/4<\/td><td class=\"column-3\">Diffusion<\/td>\n<\/tr>\n<tr class=\"row-40\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Black Pro Mist 1\/2<\/td><td class=\"column-3\">Diffusion<\/td>\n<\/tr>\n<tr class=\"row-41\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Black Pro Mist 1<\/td><td class=\"column-3\">Diffusion<\/td>\n<\/tr>\n<tr class=\"row-42\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Enhancing<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-43\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Chocolate 1<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-44\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Chocolate 2<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-45\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Chocolate 3<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-46\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">UV Haze 1<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-47\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Straw 1<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-48\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Straw 2<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-49\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Straw 3<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-50\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Sepia 1<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-51\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Sepia 2<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-52\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Sepia 3<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-53\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Black Diffusion 1\/4<\/td><td class=\"column-3\">Diffusion<\/td>\n<\/tr>\n<tr class=\"row-54\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Black Diffusion 1\/2<\/td><td class=\"column-3\">Diffusion<\/td>\n<\/tr>\n<tr class=\"row-55\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Black Diffusion 1<\/td><td class=\"column-3\">Diffusion<\/td>\n<\/tr>\n<tr class=\"row-56\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Black Diffusion 2<\/td><td class=\"column-3\">Diffusion<\/td>\n<\/tr>\n<tr class=\"row-57\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Black Diffusion 3<\/td><td class=\"column-3\">Diffusion<\/td>\n<\/tr>\n<tr class=\"row-58\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Tobacco 1<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-59\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Tobacco 2<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-60\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Tobacco 3<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-61\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Low Contrast 1<\/td><td class=\"column-3\">Contrast<\/td>\n<\/tr>\n<tr class=\"row-62\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Low Contrast 2<\/td><td class=\"column-3\">Contrast<\/td>\n<\/tr>\n<tr class=\"row-63\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Low Contrast 3<\/td><td class=\"column-3\">Contrast<\/td>\n<\/tr>\n<tr class=\"row-64\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Low Contrast 4<\/td><td class=\"column-3\">Contrast<\/td>\n<\/tr>\n<tr class=\"row-65\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Low Contrast 5<\/td><td class=\"column-3\">Contrast<\/td>\n<\/tr>\n<tr class=\"row-66\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Ultra Contrast 1<\/td><td class=\"column-3\">Contrast<\/td>\n<\/tr>\n<tr class=\"row-67\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Ultra Contrast 2<\/td><td class=\"column-3\">Contrast<\/td>\n<\/tr>\n<tr class=\"row-68\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Ultra Contrast 3<\/td><td class=\"column-3\">Contrast<\/td>\n<\/tr>\n<tr class=\"row-69\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Ultra Contrast 4<\/td><td class=\"column-3\">Contrast<\/td>\n<\/tr>\n<tr class=\"row-70\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Ultra Contrast 5<\/td><td class=\"column-3\">Contrast<\/td>\n<\/tr>\n<tr class=\"row-71\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Double Fog 1<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-72\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Double Fog 2<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-73\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Double Fog 3<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-74\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Double Fog 4<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-75\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Double Fog 5<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-76\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Fog 1<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-77\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Fog 2<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-78\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Fog 3<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-79\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Fog 4<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-80\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Fog 5<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-81\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Sunset Grade Soft 1<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-82\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Sunset Grade Soft 2<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-83\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Sunset Grade Soft 3<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-84\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">85<\/td><td class=\"column-3\">Analogue<\/td>\n<\/tr>\n<tr class=\"row-85\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">85 ND 0.3<\/td><td class=\"column-3\">Analogue<\/td>\n<\/tr>\n<tr class=\"row-86\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">85 ND 0.6<\/td><td class=\"column-3\">Analogue<\/td>\n<\/tr>\n<tr class=\"row-87\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">85 ND 0.9<\/td><td class=\"column-3\">Analogue<\/td>\n<\/tr>\n<tr class=\"row-88\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">85 ND Pole<\/td><td class=\"column-3\">Analogue<\/td>\n<\/tr>\n<tr class=\"row-89\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">ND Grad Soft SFX 0.3<\/td><td class=\"column-3\">Diffusion<\/td>\n<\/tr>\n<tr class=\"row-90\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Star 4pt 2mm<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-91\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Star 4pt 3mm<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-92\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Star 4pt 4mm<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-93\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Star 6pt 3mm<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-94\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Star 6pt 4mm<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-95\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Star 8pt 3mm<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-96\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Star 8pt 4mm<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-97\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Day for Night mono<\/td><td class=\"column-3\">Effect<\/td>\n<\/tr>\n<tr class=\"row-98\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">82 A<\/td><td class=\"column-3\">Analogue<\/td>\n<\/tr>\n<tr class=\"row-99\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">82 B<\/td><td class=\"column-3\">Analogue<\/td>\n<\/tr>\n<tr class=\"row-100\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">82 C<\/td><td class=\"column-3\">Analogue<\/td>\n<\/tr>\n<tr class=\"row-101\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">81 A<\/td><td class=\"column-3\">Analogue<\/td>\n<\/tr>\n<tr class=\"row-102\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">81 B<\/td><td class=\"column-3\">Analogue<\/td>\n<\/tr>\n<tr class=\"row-103\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">81 C<\/td><td class=\"column-3\">Analogue<\/td>\n<\/tr>\n<tr class=\"row-104\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">81 D<\/td><td class=\"column-3\">Analogue<\/td>\n<\/tr>\n<tr class=\"row-105\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">80 A<\/td><td class=\"column-3\">Analogue<\/td>\n<\/tr>\n<tr class=\"row-106\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">80 B<\/td><td class=\"column-3\">Analogue<\/td>\n<\/tr>\n<tr class=\"row-107\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">80 C<\/td><td class=\"column-3\">Analogue<\/td>\n<\/tr>\n<tr class=\"row-108\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">81EF<\/td><td class=\"column-3\">Analogue<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-4 from cache --><\/details>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary>Filter 138mm<\/summary>\n<table id=\"tablepress-5\" class=\"tablepress tablepress-id-5\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">Brand<\/th><th class=\"column-2\">Type<\/th><th class=\"column-3\">Category<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">True pole linear<\/td><td class=\"column-3\">Pola \/ Clear<\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Clear<\/td><td class=\"column-3\">Pola \/ Clear<\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">ND 0.3<\/td><td class=\"column-3\">ND<\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">ND 0.6<\/td><td class=\"column-3\">ND<\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">ND 0.9<\/td><td class=\"column-3\">ND<\/td>\n<\/tr>\n<tr class=\"row-7\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">ND 1.2<\/td><td class=\"column-3\">ND<\/td>\n<\/tr>\n<tr class=\"row-8\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">85<\/td><td class=\"column-3\">Analogue<\/td>\n<\/tr>\n<tr class=\"row-9\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">85 ND 0.3<\/td><td class=\"column-3\">Analogue<\/td>\n<\/tr>\n<tr class=\"row-10\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">85 ND 0.6<\/td><td class=\"column-3\">Analogue<\/td>\n<\/tr>\n<tr class=\"row-11\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">85 ND 0.9<\/td><td class=\"column-3\">Analogue<\/td>\n<\/tr>\n<tr class=\"row-12\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">85 Polariser<\/td><td class=\"column-3\">Analogue<\/td>\n<\/tr>\n<tr class=\"row-13\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Polariser<\/td><td class=\"column-3\">Pola \/ Clear<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-5 from cache --><\/details>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary>Filter with thread<\/summary>\n<table id=\"tablepress-6\" class=\"tablepress tablepress-id-6\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">Brand<\/th><th class=\"column-2\">Type<\/th><th class=\"column-3\">Size<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\">Hoya<\/td><td class=\"column-2\">Circular pole<\/td><td class=\"column-3\">77mm<\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">Hoya<\/td><td class=\"column-2\">Circular pole<\/td><td class=\"column-3\">82mm<\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">B+W<\/td><td class=\"column-2\">Variable ND<\/td><td class=\"column-3\">82mm<\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Step-Up Ring 58-77mm<\/td><td class=\"column-3\">58-77mm<\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Step-Up Ring 67-77mm<\/td><td class=\"column-3\">67-77mm<\/td>\n<\/tr>\n<tr class=\"row-7\">\n\t<td class=\"column-1\">Tiffen<\/td><td class=\"column-2\">Step-Up Ring 72-77mm<\/td><td class=\"column-3\">72-77mm<\/td>\n<\/tr>\n<tr class=\"row-8\">\n\t<td class=\"column-1\">B+W<\/td><td class=\"column-2\">Variable ND<\/td><td class=\"column-3\">77mm<\/td>\n<\/tr>\n<tr class=\"row-9\">\n\t<td class=\"column-1\">B+W<\/td><td class=\"column-2\">Variable ND<\/td><td class=\"column-3\">82mm<\/td>\n<\/tr>\n<tr class=\"row-10\">\n\t<td class=\"column-1\">Tailor<\/td><td class=\"column-2\">Hollywood Black Magic 1\/8<\/td><td class=\"column-3\">82mm<\/td>\n<\/tr>\n<tr class=\"row-11\">\n\t<td class=\"column-1\">B+W<\/td><td class=\"column-2\">Variable ND<\/td><td class=\"column-3\">67mm<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-6 from cache --><\/details>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>Large selection of various filters.<\/p>","protected":false},"featured_media":5059,"parent":0,"menu_order":203,"template":"","meta":{"_acf_changed":false,"content-type":""},"categories":[24],"tags":[253,255,254],"class_list":["post-5051","geraet","type-geraet","status-publish","has-post-thumbnail","hentry","category-verleih","tag-filter","tag-schneider","tag-tiffen"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Filter Tabelle - Cinegrell Z\u00fcrich<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cinegrell.ch\/en\/geraet\/filter-4x4\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Filter Tabelle - Cinegrell Z\u00fcrich\" \/>\n<meta property=\"og:description\" content=\"Grosse Auswahl an diversen Filtern.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cinegrell.ch\/en\/geraet\/filter-4x4\/\" \/>\n<meta property=\"og:site_name\" content=\"Cinegrell Z\u00fcrich\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cinegrell\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-30T13:35:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cinegrell.ch\/wp-content\/uploads\/2025\/02\/filter-4x4-1.avif\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1103\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cinegrell.ch\\\/geraet\\\/filter-4x4\\\/\",\"url\":\"https:\\\/\\\/cinegrell.ch\\\/geraet\\\/filter-4x4\\\/\",\"name\":\"Filter Tabelle - Cinegrell Z\u00fcrich\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cinegrell.ch\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cinegrell.ch\\\/geraet\\\/filter-4x4\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cinegrell.ch\\\/geraet\\\/filter-4x4\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cinegrell.ch\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/filter-4x4-1.avif\",\"datePublished\":\"2025-02-20T09:48:57+00:00\",\"dateModified\":\"2025-06-30T13:35:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cinegrell.ch\\\/geraet\\\/filter-4x4\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cinegrell.ch\\\/geraet\\\/filter-4x4\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/cinegrell.ch\\\/geraet\\\/filter-4x4\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cinegrell.ch\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/filter-4x4-1.avif\",\"contentUrl\":\"https:\\\/\\\/cinegrell.ch\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/filter-4x4-1.avif\",\"width\":1200,\"height\":1103},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cinegrell.ch\\\/geraet\\\/filter-4x4\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/cinegrell.ch\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Filter Tabelle\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cinegrell.ch\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/cinegrell.ch\\\/en\\\/\",\"name\":\"Cinegrell Z\u00fcrich\",\"description\":\"Der Rundum-Dienstleister f\u00fcr Filmprojekte\",\"publisher\":{\"@id\":\"https:\\\/\\\/cinegrell.ch\\\/en\\\/#organization\"},\"alternateName\":\"Cinegrell Rental\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cinegrell.ch\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cinegrell.ch\\\/en\\\/#organization\",\"name\":\"Cinegrell Z\u00fcrich\",\"url\":\"https:\\\/\\\/cinegrell.ch\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/cinegrell.ch\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cinegrell.ch\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/cg_site_logo_zrh.avif\",\"contentUrl\":\"https:\\\/\\\/cinegrell.ch\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/cg_site_logo_zrh.avif\",\"width\":1341,\"height\":389,\"caption\":\"Cinegrell Z\u00fcrich\"},\"image\":{\"@id\":\"https:\\\/\\\/cinegrell.ch\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/cinegrell\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Filter Tabelle - Cinegrell Z\u00fcrich","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cinegrell.ch\/en\/geraet\/filter-4x4\/","og_locale":"en_GB","og_type":"article","og_title":"Filter Tabelle - Cinegrell Z\u00fcrich","og_description":"Grosse Auswahl an diversen Filtern.","og_url":"https:\/\/cinegrell.ch\/en\/geraet\/filter-4x4\/","og_site_name":"Cinegrell Z\u00fcrich","article_publisher":"https:\/\/www.facebook.com\/cinegrell\/","article_modified_time":"2025-06-30T13:35:28+00:00","og_image":[{"width":1200,"height":1103,"url":"https:\/\/cinegrell.ch\/wp-content\/uploads\/2025\/02\/filter-4x4-1.avif","type":"image\/webp"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cinegrell.ch\/geraet\/filter-4x4\/","url":"https:\/\/cinegrell.ch\/geraet\/filter-4x4\/","name":"Filter Tabelle - Cinegrell Z\u00fcrich","isPartOf":{"@id":"https:\/\/cinegrell.ch\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cinegrell.ch\/geraet\/filter-4x4\/#primaryimage"},"image":{"@id":"https:\/\/cinegrell.ch\/geraet\/filter-4x4\/#primaryimage"},"thumbnailUrl":"https:\/\/cinegrell.ch\/wp-content\/uploads\/2025\/02\/filter-4x4-1.avif","datePublished":"2025-02-20T09:48:57+00:00","dateModified":"2025-06-30T13:35:28+00:00","breadcrumb":{"@id":"https:\/\/cinegrell.ch\/geraet\/filter-4x4\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cinegrell.ch\/geraet\/filter-4x4\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/cinegrell.ch\/geraet\/filter-4x4\/#primaryimage","url":"https:\/\/cinegrell.ch\/wp-content\/uploads\/2025\/02\/filter-4x4-1.avif","contentUrl":"https:\/\/cinegrell.ch\/wp-content\/uploads\/2025\/02\/filter-4x4-1.avif","width":1200,"height":1103},{"@type":"BreadcrumbList","@id":"https:\/\/cinegrell.ch\/geraet\/filter-4x4\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/cinegrell.ch\/"},{"@type":"ListItem","position":2,"name":"Filter Tabelle"}]},{"@type":"WebSite","@id":"https:\/\/cinegrell.ch\/en\/#website","url":"https:\/\/cinegrell.ch\/en\/","name":"Cinegrell Zurich","description":"The all-round service provider for film projects","publisher":{"@id":"https:\/\/cinegrell.ch\/en\/#organization"},"alternateName":"Cinegrell Rental","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cinegrell.ch\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/cinegrell.ch\/en\/#organization","name":"Cinegrell Zurich","url":"https:\/\/cinegrell.ch\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/cinegrell.ch\/en\/#\/schema\/logo\/image\/","url":"https:\/\/cinegrell.ch\/wp-content\/uploads\/2024\/12\/cg_site_logo_zrh.avif","contentUrl":"https:\/\/cinegrell.ch\/wp-content\/uploads\/2024\/12\/cg_site_logo_zrh.avif","width":1341,"height":389,"caption":"Cinegrell Z\u00fcrich"},"image":{"@id":"https:\/\/cinegrell.ch\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cinegrell\/"]}]}},"_links":{"self":[{"href":"https:\/\/cinegrell.ch\/en\/wp-json\/wp\/v2\/geraet\/5051","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cinegrell.ch\/en\/wp-json\/wp\/v2\/geraet"}],"about":[{"href":"https:\/\/cinegrell.ch\/en\/wp-json\/wp\/v2\/types\/geraet"}],"version-history":[{"count":1,"href":"https:\/\/cinegrell.ch\/en\/wp-json\/wp\/v2\/geraet\/5051\/revisions"}],"predecessor-version":[{"id":7498,"href":"https:\/\/cinegrell.ch\/en\/wp-json\/wp\/v2\/geraet\/5051\/revisions\/7498"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cinegrell.ch\/en\/wp-json\/wp\/v2\/media\/5059"}],"wp:attachment":[{"href":"https:\/\/cinegrell.ch\/en\/wp-json\/wp\/v2\/media?parent=5051"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cinegrell.ch\/en\/wp-json\/wp\/v2\/categories?post=5051"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cinegrell.ch\/en\/wp-json\/wp\/v2\/tags?post=5051"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}