{"id":4720,"date":"2025-02-18T11:22:23","date_gmt":"2025-02-18T11:22:23","guid":{"rendered":"https:\/\/cinegrell.ch\/?post_type=geraet&#038;p=4720"},"modified":"2026-06-19T11:29:31","modified_gmt":"2026-06-19T11:29:31","slug":"tv-logic-lvm-075a-7-monitor","status":"publish","type":"geraet","link":"https:\/\/cinegrell.ch\/en\/geraet\/tv-logic-lvm-075a-7-monitor\/","title":{"rendered":"TV-Logic LVM-075A 7\u2033 monitor"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Portable, lightweight monitor with protective cover.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>HD-SDI In\/Out<\/li>\n\n\n\n<li>HDMI In\/Out<\/li>\n\n\n\n<li>V-Mount battery plate<\/li>\n\n\n\n<li>Sunhood<\/li>\n\n\n\n<li>Protective cover<\/li>\n\n\n\n<li>LCD 1920 \u00d7 1080<\/li>\n\n\n\n<li>600 nits<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Link to the manufacturer: <a href=\"https:\/\/www.tvlogic.tv\/new\/M_Spec.asp?sidx=75\" target=\"_blank\" rel=\"noreferrer noopener\">TV-Logic<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>Wireless control room \/ focus monitor.<\/p>","protected":false},"featured_media":4721,"parent":0,"menu_order":260,"template":"","meta":{"_acf_changed":false,"content-type":""},"categories":[24,29],"tags":[192,191,210,169],"class_list":["post-4720","geraet","type-geraet","status-publish","has-post-thumbnail","hentry","category-verleih","category-verleih-video","tag-monitor","tag-tv","tag-tv-logic","tag-video"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>TV-Logic LVM-075A 7&quot; Monitor - Cinegrell Z\u00fcrich<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cinegrell.ch\/en\/geraet\/tv-logic-lvm-075a-7-monitor\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TV-Logic LVM-075A 7&quot; Monitor - Cinegrell Z\u00fcrich\" \/>\n<meta property=\"og:description\" content=\"Wireless Regie \/ Focus Monitor.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cinegrell.ch\/en\/geraet\/tv-logic-lvm-075a-7-monitor\/\" \/>\n<meta property=\"og:site_name\" content=\"Cinegrell Z\u00fcrich\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cinegrell\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-19T11:29:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cinegrell.ch\/wp-content\/uploads\/2025\/02\/TvLogic-7-zoll.avif\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1103\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cinegrell.ch\\\/geraet\\\/tv-logic-lvm-075a-7-monitor\\\/\",\"url\":\"https:\\\/\\\/cinegrell.ch\\\/geraet\\\/tv-logic-lvm-075a-7-monitor\\\/\",\"name\":\"TV-Logic LVM-075A 7\\\" Monitor - Cinegrell Z\u00fcrich\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cinegrell.ch\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cinegrell.ch\\\/geraet\\\/tv-logic-lvm-075a-7-monitor\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cinegrell.ch\\\/geraet\\\/tv-logic-lvm-075a-7-monitor\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cinegrell.ch\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/TvLogic-7-zoll.avif\",\"datePublished\":\"2025-02-18T11:22:23+00:00\",\"dateModified\":\"2026-06-19T11:29:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cinegrell.ch\\\/geraet\\\/tv-logic-lvm-075a-7-monitor\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cinegrell.ch\\\/geraet\\\/tv-logic-lvm-075a-7-monitor\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/cinegrell.ch\\\/geraet\\\/tv-logic-lvm-075a-7-monitor\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cinegrell.ch\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/TvLogic-7-zoll.avif\",\"contentUrl\":\"https:\\\/\\\/cinegrell.ch\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/TvLogic-7-zoll.avif\",\"width\":1200,\"height\":1103},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cinegrell.ch\\\/geraet\\\/tv-logic-lvm-075a-7-monitor\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/cinegrell.ch\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"TV-Logic LVM-075A 7&#8243; Monitor\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cinegrell.ch\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/cinegrell.ch\\\/en\\\/\",\"name\":\"Cinegrell Z\u00fcrich\",\"description\":\"Der Rundum-Dienstleister f\u00fcr Filmprojekte\",\"publisher\":{\"@id\":\"https:\\\/\\\/cinegrell.ch\\\/en\\\/#organization\"},\"alternateName\":\"Cinegrell Rental\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cinegrell.ch\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cinegrell.ch\\\/en\\\/#organization\",\"name\":\"Cinegrell Z\u00fcrich\",\"url\":\"https:\\\/\\\/cinegrell.ch\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/cinegrell.ch\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cinegrell.ch\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/cg_site_logo_zrh.avif\",\"contentUrl\":\"https:\\\/\\\/cinegrell.ch\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/cg_site_logo_zrh.avif\",\"width\":1341,\"height\":389,\"caption\":\"Cinegrell Z\u00fcrich\"},\"image\":{\"@id\":\"https:\\\/\\\/cinegrell.ch\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/cinegrell\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"TV-Logic LVM-075A 7\" Monitor - Cinegrell Z\u00fcrich","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cinegrell.ch\/en\/geraet\/tv-logic-lvm-075a-7-monitor\/","og_locale":"en_GB","og_type":"article","og_title":"TV-Logic LVM-075A 7\" Monitor - Cinegrell Z\u00fcrich","og_description":"Wireless Regie \/ Focus Monitor.","og_url":"https:\/\/cinegrell.ch\/en\/geraet\/tv-logic-lvm-075a-7-monitor\/","og_site_name":"Cinegrell Z\u00fcrich","article_publisher":"https:\/\/www.facebook.com\/cinegrell\/","article_modified_time":"2026-06-19T11:29:31+00:00","og_image":[{"width":1200,"height":1103,"url":"https:\/\/cinegrell.ch\/wp-content\/uploads\/2025\/02\/TvLogic-7-zoll.avif","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cinegrell.ch\/geraet\/tv-logic-lvm-075a-7-monitor\/","url":"https:\/\/cinegrell.ch\/geraet\/tv-logic-lvm-075a-7-monitor\/","name":"TV-Logic LVM-075A 7\" Monitor - Cinegrell Z\u00fcrich","isPartOf":{"@id":"https:\/\/cinegrell.ch\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cinegrell.ch\/geraet\/tv-logic-lvm-075a-7-monitor\/#primaryimage"},"image":{"@id":"https:\/\/cinegrell.ch\/geraet\/tv-logic-lvm-075a-7-monitor\/#primaryimage"},"thumbnailUrl":"https:\/\/cinegrell.ch\/wp-content\/uploads\/2025\/02\/TvLogic-7-zoll.avif","datePublished":"2025-02-18T11:22:23+00:00","dateModified":"2026-06-19T11:29:31+00:00","breadcrumb":{"@id":"https:\/\/cinegrell.ch\/geraet\/tv-logic-lvm-075a-7-monitor\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cinegrell.ch\/geraet\/tv-logic-lvm-075a-7-monitor\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/cinegrell.ch\/geraet\/tv-logic-lvm-075a-7-monitor\/#primaryimage","url":"https:\/\/cinegrell.ch\/wp-content\/uploads\/2025\/02\/TvLogic-7-zoll.avif","contentUrl":"https:\/\/cinegrell.ch\/wp-content\/uploads\/2025\/02\/TvLogic-7-zoll.avif","width":1200,"height":1103},{"@type":"BreadcrumbList","@id":"https:\/\/cinegrell.ch\/geraet\/tv-logic-lvm-075a-7-monitor\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/cinegrell.ch\/"},{"@type":"ListItem","position":2,"name":"TV-Logic LVM-075A 7&#8243; Monitor"}]},{"@type":"WebSite","@id":"https:\/\/cinegrell.ch\/en\/#website","url":"https:\/\/cinegrell.ch\/en\/","name":"Cinegrell Zurich","description":"The all-round service provider for film projects","publisher":{"@id":"https:\/\/cinegrell.ch\/en\/#organization"},"alternateName":"Cinegrell Rental","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cinegrell.ch\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/cinegrell.ch\/en\/#organization","name":"Cinegrell Zurich","url":"https:\/\/cinegrell.ch\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/cinegrell.ch\/en\/#\/schema\/logo\/image\/","url":"https:\/\/cinegrell.ch\/wp-content\/uploads\/2024\/12\/cg_site_logo_zrh.avif","contentUrl":"https:\/\/cinegrell.ch\/wp-content\/uploads\/2024\/12\/cg_site_logo_zrh.avif","width":1341,"height":389,"caption":"Cinegrell Z\u00fcrich"},"image":{"@id":"https:\/\/cinegrell.ch\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cinegrell\/"]}]}},"_links":{"self":[{"href":"https:\/\/cinegrell.ch\/en\/wp-json\/wp\/v2\/geraet\/4720","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cinegrell.ch\/en\/wp-json\/wp\/v2\/geraet"}],"about":[{"href":"https:\/\/cinegrell.ch\/en\/wp-json\/wp\/v2\/types\/geraet"}],"version-history":[{"count":2,"href":"https:\/\/cinegrell.ch\/en\/wp-json\/wp\/v2\/geraet\/4720\/revisions"}],"predecessor-version":[{"id":9444,"href":"https:\/\/cinegrell.ch\/en\/wp-json\/wp\/v2\/geraet\/4720\/revisions\/9444"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cinegrell.ch\/en\/wp-json\/wp\/v2\/media\/4721"}],"wp:attachment":[{"href":"https:\/\/cinegrell.ch\/en\/wp-json\/wp\/v2\/media?parent=4720"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cinegrell.ch\/en\/wp-json\/wp\/v2\/categories?post=4720"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cinegrell.ch\/en\/wp-json\/wp\/v2\/tags?post=4720"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}